{"id":568,"count":1,"description":"","link":"https:\/\/citygreenlight.com\/en\/category\/sustainable-mobility\/","name":"Sustainable mobility","slug":"sustainable-mobility","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sustainable mobility Archivi - City Green Light<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/citygreenlight.com\/en\/category\/sustainable-mobility\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sustainable mobility Archivi - City Green Light\" \/>\n<meta property=\"og:url\" content=\"https:\/\/citygreenlight.com\/en\/category\/sustainable-mobility\/\" \/>\n<meta property=\"og:site_name\" content=\"City Green Light\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/category\\\/sustainable-mobility\\\/\",\"url\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/category\\\/sustainable-mobility\\\/\",\"name\":\"Sustainable mobility Archivi - City Green Light\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/category\\\/sustainable-mobility\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/category\\\/sustainable-mobility\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sustainable mobility\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/\",\"name\":\"City Green Light\",\"description\":\"Efficienza energetica e innovazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/#organization\",\"name\":\"City Green Light S.p.A.\",\"url\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/citygreenlight.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-CGL.svg\",\"contentUrl\":\"https:\\\/\\\/citygreenlight.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-CGL.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"City Green Light S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/citygreenlight.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CityGreenLight\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sustainable mobility Archivi - City Green Light","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/citygreenlight.com\/en\/category\/sustainable-mobility\/","og_locale":"en_US","og_type":"article","og_title":"Sustainable mobility Archivi - City Green Light","og_url":"https:\/\/citygreenlight.com\/en\/category\/sustainable-mobility\/","og_site_name":"City Green Light","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/citygreenlight.com\/en\/category\/sustainable-mobility\/","url":"https:\/\/citygreenlight.com\/en\/category\/sustainable-mobility\/","name":"Sustainable mobility Archivi - City Green Light","isPartOf":{"@id":"https:\/\/citygreenlight.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/citygreenlight.com\/en\/category\/sustainable-mobility\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/citygreenlight.com\/en\/category\/sustainable-mobility\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/citygreenlight.com\/en\/"},{"@type":"ListItem","position":2,"name":"Sustainable mobility"}]},{"@type":"WebSite","@id":"https:\/\/citygreenlight.com\/en\/#website","url":"https:\/\/citygreenlight.com\/en\/","name":"City Green Light","description":"Efficienza energetica e innovazione","publisher":{"@id":"https:\/\/citygreenlight.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/citygreenlight.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/citygreenlight.com\/en\/#organization","name":"City Green Light S.p.A.","url":"https:\/\/citygreenlight.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/citygreenlight.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/citygreenlight.com\/wp-content\/uploads\/2025\/06\/logo-CGL.svg","contentUrl":"https:\/\/citygreenlight.com\/wp-content\/uploads\/2025\/06\/logo-CGL.svg","width":"1024","height":"1024","caption":"City Green Light S.p.A."},"image":{"@id":"https:\/\/citygreenlight.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CityGreenLight"]}]}},"_links":{"self":[{"href":"https:\/\/citygreenlight.com\/en\/wp-json\/wp\/v2\/categories\/568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/citygreenlight.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/citygreenlight.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/citygreenlight.com\/en\/wp-json\/wp\/v2\/posts?categories=568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}